{"id":6489,"date":"2025-04-01T17:02:58","date_gmt":"2025-04-01T15:02:58","guid":{"rendered":"https:\/\/www.pocapots.es\/?post_type=product&#038;p=6489"},"modified":"2026-04-21T01:17:25","modified_gmt":"2026-04-20T23:17:25","slug":"tarta-de-manzana-y-almendras-2","status":"publish","type":"product","link":"https:\/\/www.pocapots.es\/es\/produit\/tarte-pomme-amandine\/","title":{"rendered":"tarta de manzana y almendras"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Composition<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Manzanas fundentes, una crema de almendra dulce y una masa crujiente<\/li>\n<li>Un bocado de oto\u00f1o, incluso en verano.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Consejo de maridaje<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Perfecto para cerrar una comida. Marida con un vino dulce (Sauternes, Banyuls) o un cava semi-seco bien fr\u00edo. Opcionalmente, caf\u00e9 o t\u00e9 negro para un maridaje cl\u00e1sico y limpio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entrega &#038; elaboraci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Elaborado el mismo d\u00eda en nuestras cocinas. <strong>Entrega gratuita en Barcelona desde 60 \u20ac IVA excl.<\/strong> Para pedidos &gt; 6 unidades, prever <strong>48 h de antelaci\u00f3n<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Al\u00e9rgenos: gluten, frutos de c\u00e1scara, huevos, lactosa<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Manzanas que se derriten, dulce crema de almendras y crujiente hojaldre. Un bocado de oto\u00f1o, incluso en verano.<br \/>\nAl\u00e9rgenos: gluten, frutos de c\u00e1scara, huevos, lactosa<\/p>","protected":false},"featured_media":1170,"template":"","meta":{"rank_math_title":"Tarte pomme amandine \u2014 Desserts \u00e0 Barcelone | Poc a Pots","rank_math_description":"Des pommes fondantes, une cr\u00e8me d\u2019amande douce et une p\u00e2te croustillante. Une bouch\u00e9e d\u2019automne, \u2026 Livraison Barcelone d\u00e8s 60\u20ac.","rank_math_focus_keyword":"tarte pomme amandine","rank_math_robots":null,"rank_math_canonical_url":"","rank_math_facebook_title":"","rank_math_facebook_description":"","_joinchat":[]},"product_brand":[],"product_cat":[80],"product_tag":[255,254,159],"class_list":["post-6489","product","type-product","status-publish","has-post-thumbnail","product_cat-desserts","product_tag-dessert","product_tag-farine-bio","product_tag-fruits","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/product\/6489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/media\/1170"}],"wp:attachment":[{"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/media?parent=6489"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/product_brand?post=6489"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/product_cat?post=6489"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.pocapots.es\/es\/wp-json\/wp\/v2\/product_tag?post=6489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}